{"id":2441,"date":"2022-02-12T17:07:52","date_gmt":"2022-02-12T17:07:52","guid":{"rendered":"https:\/\/www.artcomax.fr\/portfolio\/?post_type=fw-portfolio&#038;p=2441"},"modified":"2022-02-12T17:11:07","modified_gmt":"2022-02-12T17:11:07","slug":"programme-election-mairie-de-hirel","status":"publish","type":"fw-portfolio","link":"https:\/\/www.artcomax.fr\/portfolio\/project\/programme-election-mairie-de-hirel\/","title":{"rendered":"Mairie de Hirel"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2441\" class=\"elementor elementor-2441\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41f7dda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41f7dda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b7d8a4\" data-id=\"6b7d8a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2cb9b3 elementor-widget elementor-widget-wb-before-after-image-slider-elementor\" data-id=\"b2cb9b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wb-before-after-image-slider-elementor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wb_ebais_twentytwenty_container twentytwenty-container\" id=\"wb_before_after_b2cb9b3\">\r\n\t\t\t<span class='before_text'>Avant<\/span>\r\n\t\t\t<span class='after_text'>Apr\u00e8s<\/span>\r\n<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_R.jpg\" class=\"attachment-full size-full wp-image-1420\" alt=\"Plaquette Election Hirel Recto\" srcset=\"https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_R.jpg 1000w, https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_R-300x169.jpg 300w, https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_R-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><img decoding=\"async\" width=\"1000\" height=\"563\" src=\"https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_V.jpg\" class=\"attachment-full size-full wp-image-1429\" alt=\"Plaquette Election Hirel Verso\" srcset=\"https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_V.jpg 1000w, https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_V-300x169.jpg 300w, https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_V-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t<\/div>\r\n\t\t<style>\r\n\t\t\t#wb_before_after_b2cb9b3{\r\n\t\t\t\tmax-width: auto;\r\n\t\t\t}\r\n\t\t<\/style>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f59397 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f59397\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24a0895\" data-id=\"24a0895\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2920d06 elementor-widget elementor-widget-spacer\" data-id=\"2920d06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b07202 elementor-widget elementor-widget-image-gallery\" data-id=\"7b07202\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-2441 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7b07202\" data-elementor-lightbox-title=\"Plaquette Election Hirel Recto\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQyMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hcnRjb21heC5mclwvcG9ydGZvbGlvXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wMlwvVmlzdWFsX1BSSU5UMjAxNl9QbGFxdWV0dGVfRWxlY3Rpb25IaXJlbF9SLmpwZyIsInNsaWRlc2hvdyI6IjdiMDcyMDIifQ%3D%3D\" href='https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_R.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_R-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Plaquette Election Hirel Recto\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7b07202\" data-elementor-lightbox-title=\"Plaquette Election Hirel Verso\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQyOSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hcnRjb21heC5mclwvcG9ydGZvbGlvXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wMlwvVmlzdWFsX1BSSU5UMjAxNl9QbGFxdWV0dGVfRWxlY3Rpb25IaXJlbF9WLmpwZyIsInNsaWRlc2hvdyI6IjdiMDcyMDIifQ%3D%3D\" href='https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_V.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.artcomax.fr\/portfolio\/wp-content\/uploads\/2022\/02\/Visual_PRINT2016_Plaquette_ElectionHirel_V-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Plaquette Election Hirel Verso\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67463f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67463f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54654d5\" data-id=\"54654d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":1420,"template":"","fw-portfolio-category":[32,21],"class_list":["post-2441","fw-portfolio","type-fw-portfolio","status-publish","has-post-thumbnail","hentry","fw-portfolio-category-plaquette","fw-portfolio-category-print"],"_links":{"self":[{"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/fw-portfolio\/2441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/fw-portfolio"}],"about":[{"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/types\/fw-portfolio"}],"version-history":[{"count":4,"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/fw-portfolio\/2441\/revisions"}],"predecessor-version":[{"id":2446,"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/fw-portfolio\/2441\/revisions\/2446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/media\/1420"}],"wp:attachment":[{"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/media?parent=2441"}],"wp:term":[{"taxonomy":"fw-portfolio-category","embeddable":true,"href":"https:\/\/www.artcomax.fr\/portfolio\/wp-json\/wp\/v2\/fw-portfolio-category?post=2441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}